{"id":50439,"date":"2022-04-19T10:27:02","date_gmt":"2022-04-19T13:27:02","guid":{"rendered":"https:\/\/agendacomunicacao.com\/?post_type=sala-de-imprensa&#038;p=50439"},"modified":"2022-04-19T10:27:04","modified_gmt":"2022-04-19T13:27:04","slug":"pelo-terceiro-ano-consecutivo-abrace-a-serra-da-moeda-nao-sera-realizado","status":"publish","type":"sala-de-imprensa","link":"https:\/\/agendacomunicacao.com\/index.php\/sala-de-imprensa\/pelo-terceiro-ano-consecutivo-abrace-a-serra-da-moeda-nao-sera-realizado\/","title":{"rendered":"Pelo terceiro ano consecutivo Abrace a Serra da Moeda n\u00e3o ser\u00e1 realizado"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><em>Apesar do cancelamento da 15\u00aa edi\u00e7\u00e3o, ambientalistas que defendem Serra da Moeda continuam articulando a\u00e7\u00f5es junto \u00e0s esferas de poder p\u00fablico em prol da defesa das \u00e1guas subterr\u00e2neas do aqu\u00edfero montanhoso<\/em><\/p>\n\n\n\n<p>Pelo terceiro ano consecutivo o tradicional \u2018Abrace a Serra da Moeda\u2019, realizado sempre no feriado de 21 de abril pela ONG hom\u00f4nima, que atua em defesa dos recursos h\u00eddricos de uma das regi\u00f5es mais importantes de Minas Gerais, ser\u00e1 cancelado. Como o evento precisa ser planejado com v\u00e1rios meses de anteced\u00eancia e no in\u00edcio deste ano n\u00e3o havia perspectiva de arrefecimento da pandemia e da libera\u00e7\u00e3o dos espa\u00e7os p\u00fablicos para grandes encontros, devido \u00e0 dissemina\u00e7\u00e3o da variante \u00f4micron da Covid-19, os ambientalistas optaram por suspender a edi\u00e7\u00e3o que seria a de n\u00famero 15.<\/p>\n\n\n\n<p>Outro motivo que acarretou no cancelamento do abra\u00e7o simb\u00f3lico foi a interrup\u00e7\u00e3o da Avenida Nair\u00a0Martins Drumond, em Piedade do Paraopeba, distrito de Brumadinho, devido ao deslize de uma encosta da Serra da Moeda ocasionado pelas fortes chuvas de janeiro, o que coloca em risco o tr\u00e2nsito de ve\u00edculos e pessoas pela estrada de acesso ao Topo do Mundo, onde os protestos da ONG s\u00e3o realizados anualmente.<\/p>\n\n\n\n<p><strong>Reinvindica\u00e7\u00f5es continuam<\/strong><\/p>\n\n\n\n<p>Apesar do cancelamento do Abrace a Serra da Moeda, os ambientalistas que defendem a regi\u00e3o continuam articulando a\u00e7\u00f5es junto \u00e0s esferas de poder p\u00fablico em prol da defesa das \u00e1guas subterr\u00e2neas do aqu\u00edfero montanhoso. O tema, inclusive, ganha destaque nos canais digitais da ONG este ano<em>. <\/em>Oobjetivo \u00e9 ressaltar o valor desses mananciais e os riscos em rela\u00e7\u00e3o \u00e0 poss\u00edvel perda de tais fontes de abastecimento.<\/p>\n\n\n\n<p>Presidente da ONG Abrace a Serra da Moeda, o ambientalista Enio Ara\u00fajo afirma que, atualmente, o maior desafio na regi\u00e3o \u00e9 conter o avan\u00e7o predat\u00f3rio das grandes empresas, cuja atua\u00e7\u00e3o negligente vem rebaixando o len\u00e7ol fre\u00e1tico que abastece v\u00e1rias nascentes. \u201cA \u00e1gua da chuva que cair hoje levar\u00e1 de 50 a 100 anos para abastecer os aqu\u00edferos. Caso os bombeamentos sejam maiores do que o potencial de recarga [dos aqu\u00edferos], as nascentes tendem a desaparecer\u201d, destaca acrescentando que os aqu\u00edferos s\u00e3o respons\u00e1veis pela manuten\u00e7\u00e3o dos rios e c\u00f3rregos nos per\u00edodos secos.<\/p>\n\n\n\n<p>Um dos megaempreendimentos que vem contribuindo de forma nociva para o meio ambiente na Serra da Moeda \u00e9 o CSUL Lagoa dos Ingleses. Projetado para mais de 120 mil pessoas, em \u00e1rea de 27 milh\u00f5es de metros quadrados, em torno do Alphaville, condom\u00ednio nobre de Nova Lima, o CSUL ter\u00e1 demanda de mais de 2.300.000 m<sup>3<\/sup> de \u00e1gua por m\u00eas a ser retirada do aqu\u00edfero Cau\u00ea, contido no Sinclinal Moeda, o que pode colocar em risco o abastecimento para todos os munic\u00edpios da Grande Belo Horizonte.&nbsp;\u201cA regi\u00e3o onde o CSul vai se instalar \u00e9 conhecida por ser um dos mais importantes mananciais de abastecimento da regi\u00e3o metropolitana [de Belo Horizonte], sendo a Serra da Moeda um divisor de \u00e1guas entre as bacias dos rios das Velhas e Paraopeba. Mesmo sabendo disso, os respons\u00e1veis por este megaempreendimento est\u00e3o levando adiante um fara\u00f4nico projeto imobili\u00e1rio, cujos estudos hidrogeol\u00f3gicos n\u00e3o s\u00e3o conclusivos acerca da viabilidade h\u00eddrica\u201d, alerta Ara\u00fajo.<\/p>\n\n\n\n<p>Colega de Enio, o tamb\u00e9m membro da ONG, Cl\u00e9verson Vidigal ressalta, inclusive, que os empreendedores por tr\u00e1s do projeto v\u00eam encontrando brechas na legisla\u00e7\u00e3o para conseguir as licen\u00e7as de instala\u00e7\u00e3o e opera\u00e7\u00e3o concomitante, conforme DN 2017\/2017. As obras do CSUL est\u00e3o previstas para serem implantadas em quatro fases, com t\u00e9rmino estimado at\u00e9 2065.&nbsp;<\/p>\n\n\n\n<p><strong>Coca-Cola<\/strong><\/p>\n\n\n\n<p>Outro empreendimento que, segundo os ambientalistas da Abrace a Serra vem reduzindo drasticamente a vaz\u00e3o de nascentes da regi\u00e3o e comprometendo o len\u00e7ol fre\u00e1tico, \u00e9 a f\u00e1brica de refrigerantes da Coca-Cola FEMSA, instalada em Itabirito, \u00e0s margens da BR-040, em meados de 2015.&nbsp;<\/p>\n\n\n\n<p>Com capacidade para produzir 2,1 bilh\u00f5es de litros por ano, o que equivale a uma capacidade de produ\u00e7\u00e3o de 175 milh\u00f5es litros\/m\u00eas, a multinacional extrai mensalmente mais de 173.000m\u00b3<sup> <\/sup>de \u00e1gua dos mananciais subterr\u00e2neos da Serra apenas para atender a demanda de seus po\u00e7os, situados a poucas centenas de metros de aqu\u00edferos que atendem milhares de pessoas em Brumadinho. Com isso, algumas comunidades locais passaram a enfrentar uma situa\u00e7\u00e3o de desabastecimento e escassez h\u00eddrica que se arrasta por sete anos.<\/p>\n\n\n\n<p>Para contornar o problema a ONG j\u00e1 apresentou \u00e0 dire\u00e7\u00e3o da Coca-Cola, alternativas locacionais para o abastecimento dos po\u00e7os que operam na f\u00e1brica. No entanto, at\u00e9 hoje a tradicional empresa de refrigerantes se nega a estudar o assunto.<\/p>\n\n\n\n<p><strong>Mineradoras<\/strong><\/p>\n\n\n\n<p>Ainda de acordo com Cl\u00e9verson, agindo sob a coniv\u00eancia do Estado, mineradoras instaladas no Sinclinal Moeda tamb\u00e9m v\u00eam rebaixando sistematicamente o len\u00e7ol fre\u00e1tico. Isso porque, para extra\u00edrem o min\u00e9rio, as empresas t\u00eam que bombear a \u00e1gua que se encontra misturada ao min\u00e9rio. \u201cNo final de 2021, por exemplo, o Instituto Mineiro de Gest\u00e3o das \u00c1guas (IGAM) emitiu autoriza\u00e7\u00e3o para a Companhia Sider\u00fargica Nacional (CSN) rebaixar 3.130 m\u00b2\/hora, o que seria suficiente para abastecer diariamente uma cidade de 375 mil pessoas. Dessa forma, fatalmente as nascentes respons\u00e1veis pelo abastecimento de Congonhas ser\u00e3o comprometidas\u201d, alerta destacando que o rio Paraopeba, drasticamente atingido pelo desastre da Vale, em 2019, em Brumadinho, tamb\u00e9m depende dessas \u00e1guas para sua recupera\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Po\u00e7os clandestinos tamb\u00e9m preocupam<\/strong><\/p>\n\n\n\n<p>Cl\u00e9verson pontua ainda que a atua\u00e7\u00e3o de po\u00e7os clandestinos tamb\u00e9m entra na lista de problemas ambientais da Serra da Moeda. \u201cNem o pr\u00f3prio IGAM tem controle sobre eles. Com isso n\u00e3o sabemos, sequer, qual real impacto vem causando nas nascentes, em raz\u00e3o do bombeamento dos aqu\u00edferos\u201d, destaca.<\/p>\n\n\n\n<p>O desastre provocado pela Vale, em janeiro de 2019, em Brumadinho, \u00e9 outro assunto nas discuss\u00f5es que continuam sendo pautadas pela Abrace a Serra da Moeda. Desde que a lama de rejeitos da mineradora varreu vilarejos do munic\u00edpio, po\u00e7os artesianos, localizados \u00e0s margens do Rio Paraopeba, acabaram sendo afetados, o que culminou no desabastecimento de comunidades, que, desde ent\u00e3o, passaram a ser atendidas por caminh\u00f5es-pipa, fornecidos pela multinacional, em fun\u00e7\u00e3o da contamina\u00e7\u00e3o do len\u00e7ol fre\u00e1tico que alimenta esses po\u00e7os.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Agenda Comunica\u00e7\u00e3o Integrada | Assessoria de Imprensa<\/em><\/p>\n\n\n\n<p><em>Jornalistas respons\u00e1veis:&nbsp;<\/em><\/p>\n\n\n\n<p><em>Daniel de Andrade &#8211; RP 0020661-MG<\/em><\/p>\n\n\n\n<p><em>Tel&nbsp;e&nbsp;WhatsApp:&nbsp;(31)&nbsp;9 8500-1358&nbsp;<\/em><\/p>\n\n\n\n<p><em>Ma\u00edra Rolim &#8211; JP 8850- MG&nbsp;<\/em><\/p>\n\n\n\n<p><em>Tel&nbsp;e&nbsp;WhatsApp:&nbsp;(31)&nbsp;9 9120-1068<\/em><\/p>\n","protected":false},"featured_media":0,"template":"","_links":{"self":[{"href":"https:\/\/agendacomunicacao.com\/index.php\/wp-json\/wp\/v2\/sala-de-imprensa\/50439"}],"collection":[{"href":"https:\/\/agendacomunicacao.com\/index.php\/wp-json\/wp\/v2\/sala-de-imprensa"}],"about":[{"href":"https:\/\/agendacomunicacao.com\/index.php\/wp-json\/wp\/v2\/types\/sala-de-imprensa"}],"wp:attachment":[{"href":"https:\/\/agendacomunicacao.com\/index.php\/wp-json\/wp\/v2\/media?parent=50439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}