{"id":50359,"date":"2021-09-17T12:20:32","date_gmt":"2021-09-17T15:20:32","guid":{"rendered":"https:\/\/agendacomunicacao.com\/?post_type=sala-de-imprensa&#038;p=50359"},"modified":"2021-09-17T12:20:33","modified_gmt":"2021-09-17T15:20:33","slug":"gastro-hub-cria-menu-inspirado-na-primavera-2","status":"publish","type":"sala-de-imprensa","link":"https:\/\/agendacomunicacao.com\/index.php\/sala-de-imprensa\/gastro-hub-cria-menu-inspirado-na-primavera-2\/","title":{"rendered":"Gastr\u00f4 Hub cria menu inspirado na primavera"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><em>Salada tropical acompanhada de salmone siciliano custam R$ 100 por pessoa. Cliente ainda tem direito a ta\u00e7a de clericot<\/em><\/p>\n\n\n\n<p>O Gastr\u00f4 Hub, restaurante no Serra, especializado nas cozinhas italiana, chinesa, japonesa e brasileira acaba de criar um menu inspirado na primavera, esta\u00e7\u00e3o que come\u00e7a na pr\u00f3xima quarta-feira (22). Todos os itens levam frutas na receita.<\/p>\n\n\n\n<p>De entrada, salada tropical, feita com mix de folhas, peras ao vinho, gergelim e redu\u00e7\u00e3o de vinagre bals\u00e2mico. O prato principal \u00e9 um salmone siciliano (salm\u00e3o grelhado ao molho de lim\u00e3o siciliano acompanhado de arroz com castanhas e legumes \u00e0 manteiga. A entrada e o prato principal custam R$ 100 por pessoa. Ao optar pelo menu, v\u00e1lido apenas para consumo na casa de 22 de setembro at\u00e9 o fim da primavera, em 21 de dezembro, os clientes ganham uma ta\u00e7a de clericot, espumante com mix de frutas.<\/p>\n\n\n\n<p>Segundo o chef Uando Santos, respons\u00e1vel pela cozinha do estabelecimento, a ideia \u00e9 apostar em itens leves, t\u00edpicos da primavera. \u201c\u00c9 uma esta\u00e7\u00e3o que pede frescor, cores e sabor. A nossa proposta \u00e9 reunir tudo isso neste combo\u201d.<\/p>\n\n\n\n<p><strong><em>Servi\u00e7o<\/em><\/strong><\/p>\n\n\n\n<p><em>Menu Primavera Gastr\u00f4 Hub<\/em><\/p>\n\n\n\n<p><em>Salada tropical + salmone siciliano + ta\u00e7a de clericot de brinde: R$ 100 por pessoa<\/em><em><\/em><\/p>\n\n\n\n<p><em>Menu v\u00e1lido para consumo na casa de 22 de setembro \u00e0 21 de dezembro<\/em><em><\/em><\/p>\n\n\n\n<p><em>Endere\u00e7o: Av. do Contorno, 4667 \u2013 Serra<\/em><em><\/em><\/p>\n\n\n\n<p><em>Instagram: @gastrohub.bh<\/em><em><\/em><\/p>\n\n\n\n<p><em>Hor\u00e1rio de funcionamento<\/em><\/p>\n\n\n\n<p><em>Segunda a sexta-feira: 11h \u00e0s 15h | 18h \u00e0s 22h<\/em><em><\/em><\/p>\n\n\n\n<p><em>S\u00e1bado e Domingo: 11h \u00e0s 22h<\/em><em><\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Agenda Comunica\u00e7\u00e3o Integrada<\/strong><\/p>\n\n\n\n<p><em>Jornalistas respons\u00e1veis:<\/em><\/p>\n\n\n\n<p><em>Ma\u00edra Rolim &#8211; JP 8850- MG<\/em><\/p>\n\n\n\n<p><em>Daniel de Andrade &#8211; RP 0020661-MG<\/em><\/p>\n\n\n\n<p><em>(31) 3021-0204 | 9 8500-1358 | 9 9120-1068<\/em><\/p>\n\n\n\n<p><a href=\"http:\/\/www.agendacomunicacao.com\"><em>www.agendacomunicacao.com<\/em><\/a><\/p>\n","protected":false},"featured_media":0,"template":"","_links":{"self":[{"href":"https:\/\/agendacomunicacao.com\/index.php\/wp-json\/wp\/v2\/sala-de-imprensa\/50359"}],"collection":[{"href":"https:\/\/agendacomunicacao.com\/index.php\/wp-json\/wp\/v2\/sala-de-imprensa"}],"about":[{"href":"https:\/\/agendacomunicacao.com\/index.php\/wp-json\/wp\/v2\/types\/sala-de-imprensa"}],"wp:attachment":[{"href":"https:\/\/agendacomunicacao.com\/index.php\/wp-json\/wp\/v2\/media?parent=50359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}